{"id":17,"count":1,"description":"","link":"https:\/\/djdarren.site\/archive\/tag\/nowplaying\/","name":"#NowPlaying","slug":"nowplaying","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/djdarren.site\/archive\/wp-json\/wp\/v2\/tags\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/djdarren.site\/archive\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/djdarren.site\/archive\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/djdarren.site\/archive\/wp-json\/wp\/v2\/posts?tags=17"},{"href":"https:\/\/djdarren.site\/archive\/wp-json\/wp\/v2\/podcast?tags=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}